{"id":171,"date":"2024-01-08T11:02:42","date_gmt":"2024-01-08T10:02:42","guid":{"rendered":"https:\/\/esthetiquekm.com\/?page_id=171"},"modified":"2025-09-27T11:09:02","modified_gmt":"2025-09-27T09:09:02","slug":"soins-du-visage","status":"publish","type":"page","link":"https:\/\/esthetiquekm.com\/index.php\/soins-du-visage\/","title":{"rendered":"Soins du visage"},"content":{"rendered":"\n<p class=\"has-luminous-vivid-orange-color has-text-color has-link-color has-medium-font-size wp-elements-1 wp-block-paragraph\"><strong><em>Endospheres Therapy Face<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Endospheres Therapy Face\u00ae <\/em>prend soin de la peau du visage, pour r\u00e9veiller votre beaut\u00e9 naturelle. Elle acc\u00e9l\u00e8re la production des substances de la jeunesse (collag\u00e8ne, \u00e9lastine, acide hyaluronique) pour une peau plus compacte.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Sc\u00e9ance &#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;.. 30 min &#8230;. 60 \u20ac<\/li>\n\n\n\n<li>Sc\u00e9ance &#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;.. 60 min &#8230;. 120 \u20ac<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"..\/endospheres-therapy\/\" title=\"Endosphere Face\">&gt;&gt; <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">plus d&rsquo;infos<\/mark> &lt;&lt;<\/a><\/strong><\/p>\n\n\n\n<p class=\"has-luminous-vivid-orange-color has-text-color has-link-color has-medium-font-size wp-elements-2 wp-block-paragraph\"><em><strong>Skin Ceuticals <\/strong>(anti-\u00e2ge)<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Skin Ceuticals\u00ae <\/em>est la marque n\u00b0 1 am\u00e9ricaine sp\u00e9cialis\u00e9e de l\u2019anti-\u00e2ge, reconnue mondialement, <br>dont les formules \u00ab haute efficacit\u00e9 \u00bb sont recommand\u00e9es par des dermatologues et <br>chirurgiens esth\u00e9tiques.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Visage cou et d\u00e9collet\u00e9&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;. 1h40 min &#8230;.220 \u20ac<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"..\/skin-ceuticals\/\" title=\"Skin Ceuticals\">&gt;&gt; <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">plus d&rsquo;infos<\/mark> &lt;&lt;<\/a><\/strong><\/p>\n\n\n\n<p class=\"has-luminous-vivid-orange-color has-text-color has-link-color has-medium-font-size wp-elements-3 wp-block-paragraph\"><em><strong>Facial Toning Device <\/strong>(microcourant)<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La luminoth\u00e9rapie attenue les rides, le vieillissement et l\u2019acn\u00e9, en favorisant la production de collag\u00e8ne et d\u2019elastine. R\u00e9duit la taille des pores, des taches de vieillessement cutan\u00e9e et de soleil, ainsi que la s\u00e9cr\u00e9tion de s\u00e9bum pour une peau moins grasse.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lifting, contour, muscle du visage<br><em><strong>Therapy Skin Care LED Mask Kardashian\u00ae<\/strong> <\/em>(Vogue France)<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Sc\u00e9ance &#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;..1h20 min &#8230;. 160 \u20ac<\/li>\n\n\n\n<li>Drainage lymphatique &#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;.. 60 min &#8230;..125 \u20ac<\/li>\n\n\n\n<li>Nettoyage profond &#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;. 90 min &#8230;..175 \u20ac<\/li>\n<\/ul>\n\n\n\n<p class=\"has-black-color has-luminous-vivid-amber-background-color has-text-color has-background has-link-color has-small-font-size wp-elements-4 wp-block-paragraph\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-black-color\">Tarifs au 1<sup>er<\/sup> janvier 2025 &#8211; Contactez-nous pour conna\u00eetre l&rsquo;\u00e9volution des prix.<\/mark><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Endospheres Therapy Face Endospheres Therapy Face\u00ae prend soin de la peau du visage, pour r\u00e9veiller votre beaut\u00e9 naturelle. Elle acc\u00e9l\u00e8re la production des substances de la jeunesse (collag\u00e8ne, \u00e9lastine, acide &hellip; <\/p>\n","protected":false},"author":1,"featured_media":262,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"class_list":["post-171","page","type-page","status-publish","has-post-thumbnail","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Endospheres Therapy Face Endospheres Therapy Face\u00ae prend soin de la peau du visage, pour r\u00e9veiller votre beaut\u00e9 naturelle. Elle acc\u00e9l\u00e8re la production des substances de la jeunesse (collag\u00e8ne, \u00e9lastine, acide hyaluronique) pour une peau plus compacte. Sc\u00e9ance ............................................... 30 min .... 60 \u20ac Sc\u00e9ance ............................................... 60 min .... 120 \u20ac &gt;&gt; plus d&#039;infos\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/esthetiquekm.com\/index.php\/soins-du-visage\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Kristina Meyer - Institut de beaut\u00e9 - M\u00e9decine Esth\u00e9tique\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Soins du visage - Kristina Meyer\" \/>\n\t\t<meta property=\"og:description\" content=\"Endospheres Therapy Face Endospheres Therapy Face\u00ae prend soin de la peau du visage, pour r\u00e9veiller votre beaut\u00e9 naturelle. Elle acc\u00e9l\u00e8re la production des substances de la jeunesse (collag\u00e8ne, \u00e9lastine, acide hyaluronique) pour une peau plus compacte. Sc\u00e9ance ............................................... 30 min .... 60 \u20ac Sc\u00e9ance ............................................... 60 min .... 120 \u20ac &gt;&gt; plus d&#039;infos\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/esthetiquekm.com\/index.php\/soins-du-visage\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-01-08T10:02:42+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-09-27T09:09:02+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Soins du visage - Kristina Meyer\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Endospheres Therapy Face Endospheres Therapy Face\u00ae prend soin de la peau du visage, pour r\u00e9veiller votre beaut\u00e9 naturelle. Elle acc\u00e9l\u00e8re la production des substances de la jeunesse (collag\u00e8ne, \u00e9lastine, acide hyaluronique) pour une peau plus compacte. Sc\u00e9ance ............................................... 30 min .... 60 \u20ac Sc\u00e9ance ............................................... 60 min .... 120 \u20ac &gt;&gt; plus d&#039;infos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/esthetiquekm.com\\\/index.php\\\/soins-du-visage\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esthetiquekm.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/esthetiquekm.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esthetiquekm.com\\\/index.php\\\/soins-du-visage\\\/#listItem\",\"name\":\"Soins du visage\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esthetiquekm.com\\\/index.php\\\/soins-du-visage\\\/#listItem\",\"position\":2,\"name\":\"Soins du visage\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esthetiquekm.com#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/esthetiquekm.com\\\/#organization\",\"name\":\"Institut Medecine Esthetique Kristina Meyer\",\"description\":\"Institut de beaut\\u00e9 - M\\u00e9decine Esth\\u00e9tique\",\"url\":\"https:\\\/\\\/esthetiquekm.com\\\/\",\"telephone\":\"+33146341510\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/esthetiquekm.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Logo-KM-or_avatar.png\",\"@id\":\"https:\\\/\\\/esthetiquekm.com\\\/index.php\\\/soins-du-visage\\\/#organizationLogo\",\"width\":512,\"height\":512},\"image\":{\"@id\":\"https:\\\/\\\/esthetiquekm.com\\\/index.php\\\/soins-du-visage\\\/#organizationLogo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/esthetiquekm.com\\\/index.php\\\/soins-du-visage\\\/#webpage\",\"url\":\"https:\\\/\\\/esthetiquekm.com\\\/index.php\\\/soins-du-visage\\\/\",\"name\":\"Soins du visage - Kristina Meyer\",\"description\":\"Endospheres Therapy Face Endospheres Therapy Face\\u00ae prend soin de la peau du visage, pour r\\u00e9veiller votre beaut\\u00e9 naturelle. Elle acc\\u00e9l\\u00e8re la production des substances de la jeunesse (collag\\u00e8ne, \\u00e9lastine, acide hyaluronique) pour une peau plus compacte. Sc\\u00e9ance ............................................... 30 min .... 60 \\u20ac Sc\\u00e9ance ............................................... 60 min .... 120 \\u20ac >> plus d'infos\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/esthetiquekm.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/esthetiquekm.com\\\/index.php\\\/soins-du-visage\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/esthetiquekm.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/fond_entete_Visage.jpg\",\"@id\":\"https:\\\/\\\/esthetiquekm.com\\\/index.php\\\/soins-du-visage\\\/#mainImage\",\"width\":1200,\"height\":258,\"caption\":\"Soins du visage, des cils et sourcils\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/esthetiquekm.com\\\/index.php\\\/soins-du-visage\\\/#mainImage\"},\"datePublished\":\"2024-01-08T11:02:42+01:00\",\"dateModified\":\"2025-09-27T11:09:02+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/esthetiquekm.com\\\/#website\",\"url\":\"https:\\\/\\\/esthetiquekm.com\\\/\",\"name\":\"Institut Medecine Esthetique Kristina Meyer\",\"alternateName\":\"Institut Medecine Esthetique KM\",\"description\":\"Institut de beaut\\u00e9 - M\\u00e9decine Esth\\u00e9tique\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/esthetiquekm.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Soins du visage - Kristina Meyer","description":"Endospheres Therapy Face Endospheres Therapy Face\u00ae prend soin de la peau du visage, pour r\u00e9veiller votre beaut\u00e9 naturelle. Elle acc\u00e9l\u00e8re la production des substances de la jeunesse (collag\u00e8ne, \u00e9lastine, acide hyaluronique) pour une peau plus compacte. Sc\u00e9ance ............................................... 30 min .... 60 \u20ac Sc\u00e9ance ............................................... 60 min .... 120 \u20ac >> plus d'infos","canonical_url":"https:\/\/esthetiquekm.com\/index.php\/soins-du-visage\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/esthetiquekm.com\/index.php\/soins-du-visage\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/esthetiquekm.com#listItem","position":1,"name":"Home","item":"https:\/\/esthetiquekm.com","nextItem":{"@type":"ListItem","@id":"https:\/\/esthetiquekm.com\/index.php\/soins-du-visage\/#listItem","name":"Soins du visage"}},{"@type":"ListItem","@id":"https:\/\/esthetiquekm.com\/index.php\/soins-du-visage\/#listItem","position":2,"name":"Soins du visage","previousItem":{"@type":"ListItem","@id":"https:\/\/esthetiquekm.com#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/esthetiquekm.com\/#organization","name":"Institut Medecine Esthetique Kristina Meyer","description":"Institut de beaut\u00e9 - M\u00e9decine Esth\u00e9tique","url":"https:\/\/esthetiquekm.com\/","telephone":"+33146341510","logo":{"@type":"ImageObject","url":"https:\/\/esthetiquekm.com\/wp-content\/uploads\/2023\/12\/Logo-KM-or_avatar.png","@id":"https:\/\/esthetiquekm.com\/index.php\/soins-du-visage\/#organizationLogo","width":512,"height":512},"image":{"@id":"https:\/\/esthetiquekm.com\/index.php\/soins-du-visage\/#organizationLogo"}},{"@type":"WebPage","@id":"https:\/\/esthetiquekm.com\/index.php\/soins-du-visage\/#webpage","url":"https:\/\/esthetiquekm.com\/index.php\/soins-du-visage\/","name":"Soins du visage - Kristina Meyer","description":"Endospheres Therapy Face Endospheres Therapy Face\u00ae prend soin de la peau du visage, pour r\u00e9veiller votre beaut\u00e9 naturelle. Elle acc\u00e9l\u00e8re la production des substances de la jeunesse (collag\u00e8ne, \u00e9lastine, acide hyaluronique) pour une peau plus compacte. Sc\u00e9ance ............................................... 30 min .... 60 \u20ac Sc\u00e9ance ............................................... 60 min .... 120 \u20ac >> plus d'infos","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/esthetiquekm.com\/#website"},"breadcrumb":{"@id":"https:\/\/esthetiquekm.com\/index.php\/soins-du-visage\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/esthetiquekm.com\/wp-content\/uploads\/2024\/01\/fond_entete_Visage.jpg","@id":"https:\/\/esthetiquekm.com\/index.php\/soins-du-visage\/#mainImage","width":1200,"height":258,"caption":"Soins du visage, des cils et sourcils"},"primaryImageOfPage":{"@id":"https:\/\/esthetiquekm.com\/index.php\/soins-du-visage\/#mainImage"},"datePublished":"2024-01-08T11:02:42+01:00","dateModified":"2025-09-27T11:09:02+02:00"},{"@type":"WebSite","@id":"https:\/\/esthetiquekm.com\/#website","url":"https:\/\/esthetiquekm.com\/","name":"Institut Medecine Esthetique Kristina Meyer","alternateName":"Institut Medecine Esthetique KM","description":"Institut de beaut\u00e9 - M\u00e9decine Esth\u00e9tique","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/esthetiquekm.com\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"Kristina Meyer - Institut de beaut\u00e9 - M\u00e9decine Esth\u00e9tique","og:type":"article","og:title":"Soins du visage - Kristina Meyer","og:description":"Endospheres Therapy Face Endospheres Therapy Face\u00ae prend soin de la peau du visage, pour r\u00e9veiller votre beaut\u00e9 naturelle. Elle acc\u00e9l\u00e8re la production des substances de la jeunesse (collag\u00e8ne, \u00e9lastine, acide hyaluronique) pour une peau plus compacte. Sc\u00e9ance ............................................... 30 min .... 60 \u20ac Sc\u00e9ance ............................................... 60 min .... 120 \u20ac &gt;&gt; plus d'infos","og:url":"https:\/\/esthetiquekm.com\/index.php\/soins-du-visage\/","article:published_time":"2024-01-08T10:02:42+00:00","article:modified_time":"2025-09-27T09:09:02+00:00","twitter:card":"summary_large_image","twitter:title":"Soins du visage - Kristina Meyer","twitter:description":"Endospheres Therapy Face Endospheres Therapy Face\u00ae prend soin de la peau du visage, pour r\u00e9veiller votre beaut\u00e9 naturelle. Elle acc\u00e9l\u00e8re la production des substances de la jeunesse (collag\u00e8ne, \u00e9lastine, acide hyaluronique) pour une peau plus compacte. Sc\u00e9ance ............................................... 30 min .... 60 \u20ac Sc\u00e9ance ............................................... 60 min .... 120 \u20ac &gt;&gt; plus d'infos"},"aioseo_meta_data":{"post_id":"171","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2024-01-08 10:02:43","updated":"2025-09-27 09:13:54","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/esthetiquekm.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tSoins du visage\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/esthetiquekm.com"},{"label":"Soins du visage","link":"https:\/\/esthetiquekm.com\/index.php\/soins-du-visage\/"}],"_links":{"self":[{"href":"https:\/\/esthetiquekm.com\/index.php\/wp-json\/wp\/v2\/pages\/171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esthetiquekm.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/esthetiquekm.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/esthetiquekm.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/esthetiquekm.com\/index.php\/wp-json\/wp\/v2\/comments?post=171"}],"version-history":[{"count":11,"href":"https:\/\/esthetiquekm.com\/index.php\/wp-json\/wp\/v2\/pages\/171\/revisions"}],"predecessor-version":[{"id":492,"href":"https:\/\/esthetiquekm.com\/index.php\/wp-json\/wp\/v2\/pages\/171\/revisions\/492"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/esthetiquekm.com\/index.php\/wp-json\/wp\/v2\/media\/262"}],"wp:attachment":[{"href":"https:\/\/esthetiquekm.com\/index.php\/wp-json\/wp\/v2\/media?parent=171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}